

{"id":5771,"date":"2023-08-20T23:50:30","date_gmt":"2023-08-21T04:50:30","guid":{"rendered":"https:\/\/ami.advancedrenaleducation.com\/wparep\/?post_type=article&#038;p=5771"},"modified":"2025-05-09T11:17:45","modified_gmt":"2025-05-09T16:17:45","slug":"embolia-gaseosa-sp","status":"publish","type":"article","link":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/embolia-gaseosa-sp\/","title":{"rendered":"Embolia gaseosa"},"content":{"rendered":"<p>Los avances en tecnolog\u00eda y equipos han disminuido significativamente las posibilidades de embolia gaseosa durante la hemodi\u00e1lisis. La embolia gaseosa durante la di\u00e1lisis renal es extremadamente rara debido a las medidas de seguridad integradas en el equipo y los procedimientos que se utilizan actualmente. En un estudio de Tennankore y col. Todo el n\u00famero de tratamientos para tener un evento fue menos de 1 en 20,000 (1). Aunque la embolia gaseosa es poco com\u00fan, es importante comprender c\u00f3mo se desarrolla para poder tratarla y prevenirla adecuadamente.<\/p>\n<h4><strong>Etiolog\u00eda<\/strong><\/h4>\n<ul>\n<li>Puede ser venosa o, con menor frecuencia, arterial.<\/li>\n<li>Tres \u00e1reas vulnerables de entrada de aire en pacientes en di\u00e1lisis:\n<ul>\n<li>Entre el paciente y la bomba de sangre\n<ul>\n<li>Por alta presi\u00f3n negativa y fugas en el circuito en este segmento<\/li>\n<\/ul>\n<\/li>\n<li>Aire en el l\u00edquido de dializado (poco com\u00fan, la mayor\u00eda queda atrapado en la c\u00e1mara venosa)<\/li>\n<li>Durante la inserci\u00f3n o extracci\u00f3n de un cat\u00e9ter venoso central<\/li>\n<\/ul>\n<\/li>\n<li>La posici\u00f3n erguida del cuerpo y la hipovolemia reducen la presi\u00f3n venosa y son factores contribuyentes importantes<\/li>\n<\/ul>\n<h4><strong>Presentaci\u00f3n en el paciente<\/strong><\/h4>\n<ul>\n<li>Tos, dificultad para respirar<\/li>\n<li>Dolor o presi\u00f3n en el pecho<\/li>\n<li>Taquicardia<\/li>\n<li>Venas del cuello dilatadas<\/li>\n<li>Cianosis \/ color gris<\/li>\n<li>Ligera par\u00e1lisis en un lado del cuerpo (cerebral)<\/li>\n<li>Confusi\u00f3n, convulsiones, coma<\/li>\n<li>Posible paro card\u00edaco \/ respiratorio<\/li>\n<\/ul>\n<h4><strong>Tratamiento<\/strong><\/h4>\n<ul>\n<li>Evite una mayor entrada de aire sujetando y desconectando el circuito (2\u20134)<\/li>\n<li>La posici\u00f3n supina plana puede ser mejor que la posici\u00f3n lateral izquierda tradicionalmente recomendada (posici\u00f3n de Duran) y la posici\u00f3n de Trendelenburg (2-4)<\/li>\n<li>Ox\u00edgeno con FiO2 100% (4)<\/li>\n<li>Ox\u00edgeno hiperb\u00e1rico (previene el edema cerebral) (4,5)<\/li>\n<li>Uso de jeringas Luer-lock para extraer sangre de cat\u00e9teres (6)<\/li>\n<\/ul>\n<h4><strong>Prevenci\u00f3n<\/strong><\/h4>\n<ul>\n<li>Pruebe la m\u00e1quina antes de usarla para asegurarse de que el sistema de alarma del detector de aire est\u00e9 funcionando eficazmente<\/li>\n<li>La inserci\u00f3n o extracci\u00f3n del cat\u00e9ter debe realizarse en una posici\u00f3n baja con la cabeza (lugar de inserci\u00f3n 5 cm por debajo de la aur\u00edcula derecha). El paciente puede ayudar conteniendo la respiraci\u00f3n o haciendo una maniobra de Valsalva que aumentar\u00e1 la presi\u00f3n venosa central (4).<\/li>\n<\/ul>\n<div class=\"vcex-spacing\" style=\"height:30px\"><\/div><div class=\"vcex-module vcex-divider vcex-divider-solid\" style=\"width:100%;margin-top:20px;margin-bottom:20px;border-top-width:1px;border-color:#dddddd;\"><\/div>\n<h4>References<\/h4>\n<ol>\n<li>Tennankore KK, D\u2019Gama C, Faratro R, Fung S, Wong E, Chan CT. Adverse Technical Events in Home Hemodialysis. <em>Am J Kidney Dis<\/em>. 2015;65(1):116-121. Available from: http:\/\/www.ncbi.nlm.nih.gov\/pubmed\/25441436.<\/li>\n<li>Vesely TM. Air embolism during insertion of central venous catheters. <em>J Vasc Interv Radiol<\/em>. 2001;12(11):1291-1295. Available from: http:\/\/www.ncbi.nlm.nih.gov\/pubmed\/11698628.<\/li>\n<li>Muth CM, Shank ES. Gas Embolism. <em>N Engl J Med<\/em>. 2000;342(7):476-482. Available from: http:\/\/www.ncbi.nlm.nih.gov\/pubmed\/10675429.<\/li>\n<li>Palmon SC, Moore LE, Lundberg J, Toung T. Venous air embolism: a review. <em>J Clin Anesth<\/em>. 1997;9(3):251-257. Available from: http:\/\/www.ncbi.nlm.nih.gov\/pubmed\/9172037.<\/li>\n<li>Baskin SE, Wozniak RF. Hyperbaric oxygenation in the treatment of hemodialysis-associated air embolism. <em>N Engl J Med<\/em>. 1975;293(4):184-185. Available from: http:\/\/www.ncbi.nlm.nih.gov\/pubmed\/1134531.<\/li>\n<li>McCarthy C, Behravesh S, Naidu S, Oklu R. Air Embolism: Practical Tips for Prevention and Treatment. <em>J Clin Med<\/em>. 2016;5(11):93. Available from: \/pmc\/articles\/PMC5126790\/.<\/li>\n<\/ol>\n<p>P\/N 103061-01S Rev A 02\/2023<\/p>\n<div class=\"vcex-spacing\" style=\"height:30px\"><\/div>\n","protected":false},"featured_media":0,"template":"","format":"standard","meta":{"_acf_changed":false},"categories":[274],"tags":[218],"language":[42],"articles":[272],"class_list":["post-5771","article","type-article","status-publish","format-standard","hentry","category-articulos","tag-intradialytic-sp","language-spanish","articles-hemodialisis","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Embolia gaseosa - Advanced Renal Education Program<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/embolia-gaseosa-sp\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Embolia gaseosa - Advanced Renal Education Program\" \/>\n<meta property=\"og:description\" content=\"Los avances en tecnolog\u00eda y equipos han disminuido significativamente las posibilidades de embolia gaseosa durante la hemodi\u00e1lisis. La embolia gaseosa durante la di\u00e1lisis renal es extremadamente rara debido a las medidas de seguridad integradas en el equipo y los procedimientos&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/embolia-gaseosa-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"Advanced Renal Education Program\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-09T16:17:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/embolia-gaseosa-sp\/\",\"url\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/embolia-gaseosa-sp\/\",\"name\":\"Embolia gaseosa - Advanced Renal Education Program\",\"isPartOf\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#website\"},\"datePublished\":\"2023-08-21T04:50:30+00:00\",\"dateModified\":\"2025-05-09T16:17:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/embolia-gaseosa-sp\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/embolia-gaseosa-sp\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/embolia-gaseosa-sp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Embolia gaseosa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#website\",\"url\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/\",\"name\":\"Advanced Renal Education Program\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#organization\",\"name\":\"Advanced Renal Education Program\",\"url\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/03\/1Asset-1.jpg\",\"contentUrl\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/03\/1Asset-1.jpg\",\"width\":1965,\"height\":381,\"caption\":\"Advanced Renal Education Program\"},\"image\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Embolia gaseosa - Advanced Renal Education Program","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/embolia-gaseosa-sp\/","og_locale":"en_US","og_type":"article","og_title":"Embolia gaseosa - Advanced Renal Education Program","og_description":"Los avances en tecnolog\u00eda y equipos han disminuido significativamente las posibilidades de embolia gaseosa durante la hemodi\u00e1lisis. La embolia gaseosa durante la di\u00e1lisis renal es extremadamente rara debido a las medidas de seguridad integradas en el equipo y los procedimientos&hellip;","og_url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/embolia-gaseosa-sp\/","og_site_name":"Advanced Renal Education Program","article_modified_time":"2025-05-09T16:17:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/embolia-gaseosa-sp\/","url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/embolia-gaseosa-sp\/","name":"Embolia gaseosa - Advanced Renal Education Program","isPartOf":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#website"},"datePublished":"2023-08-21T04:50:30+00:00","dateModified":"2025-05-09T16:17:45+00:00","breadcrumb":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/embolia-gaseosa-sp\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/embolia-gaseosa-sp\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/embolia-gaseosa-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ami.advancedrenaleducation.com\/wparep\/"},{"@type":"ListItem","position":2,"name":"Embolia gaseosa"}]},{"@type":"WebSite","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#website","url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/","name":"Advanced Renal Education Program","description":"","publisher":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ami.advancedrenaleducation.com\/wparep\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#organization","name":"Advanced Renal Education Program","url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#\/schema\/logo\/image\/","url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/03\/1Asset-1.jpg","contentUrl":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/03\/1Asset-1.jpg","width":1965,"height":381,"caption":"Advanced Renal Education Program"},"image":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#\/schema\/logo\/image\/"}}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Advanced Renal Education Program","distributor_original_site_url":"https:\/\/ami.advancedrenaleducation.com\/wparep","push-errors":false,"_links":{"self":[{"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/article\/5771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/media?parent=5771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/categories?post=5771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/tags?post=5771"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/language?post=5771"},{"taxonomy":"articles","embeddable":true,"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/articles?post=5771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}