

{"id":5789,"date":"2023-08-24T19:50:44","date_gmt":"2023-08-25T00:50:44","guid":{"rendered":"https:\/\/ami.advancedrenaleducation.com\/wparep\/?post_type=article&#038;p=5789"},"modified":"2025-05-09T11:52:05","modified_gmt":"2025-05-09T16:52:05","slug":"comparacion-diferencia-y-significado-sp","status":"publish","type":"article","link":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/","title":{"rendered":"Comparaci\u00f3n, diferencia y significado"},"content":{"rendered":"<p>Si observamos las medias de los dos conjuntos de datos analizados en el art\u00edculo &#8220;Medidas de centralidad y dispersi\u00f3n&#8221;, podemos comparar la media del conjunto 1 (5,58) con la del conjunto 2 (8,32). Son evidentemente diferentes, pero \u00bfqu\u00e9 tan diferentes? Otra forma de hacer esta pregunta ser\u00eda: \u00bfqu\u00e9 tan fuerte es la posibilidad de que los dos conjuntos de datos (representados por sus medios) realmente representen dos poblaciones diferentes? O, \u00bfcu\u00e1l es la probabilidad de que, a pesar de la diferencia de medias, los dos conjuntos de datos realmente provengan de la misma poblaci\u00f3n? [En este contexto, poblaci\u00f3n significa un grupo de sujetos con una caracter\u00edstica \u00fanica]. Otra forma de hacer la pregunta ser\u00eda establecer una hip\u00f3tesis inicial, por ejemplo, que las medias para el conjunto 1 y el conjunto 2 son las mismas, que se denomina <strong>Hip\u00f3tesis nula<\/strong>: las medias de ambos conjuntos (poblaciones) son las mismas<sup>1<\/sup>.<\/p>\n<p>Una <strong>prueba de significancia<\/strong> es un procedimiento estad\u00edstico que determina el grado en que los datos observados son consistentes con una hip\u00f3tesis espec\u00edfica sobre una poblaci\u00f3n. Con frecuencia, a la significancia se le atribuye un valor de probabilidad, por ejemplo, la <strong>probabilidad<\/strong> de que los datos observados sean consistentes con la hip\u00f3tesis es menor que 5 en 100, lo que equivale a &lt;5%. Esta probabilidad se denotar\u00eda por &#8220;p &lt;0.05&#8221;.<\/p>\n<p>Un <strong>intervalo de confianza<\/strong> es el resultado de un procedimiento estad\u00edstico que identifica el conjunto de todos los valores plausibles de un par\u00e1metro espec\u00edfico que son consistentes con los datos observados. Un intervalo de confianza incluye todos los valores posibles de un par\u00e1metro que, si se prueba como una hip\u00f3tesis nula espec\u00edfica (ver m\u00e1s arriba) <strong>no <\/strong>nos llevar\u00eda a concluir que los datos contradicen esa hip\u00f3tesis nula en particular.<\/p>\n<p>Haciendo algunas suposiciones sobre la distribuci\u00f3n de todos los valores posibles del par\u00e1metro (por ejemplo, que los datos del par\u00e1metro est\u00e1n distribuidos normalmente; una distribuci\u00f3n de frecuencia de todos los datos se aproxima a una forma de campana sim\u00e9trica) podemos relacionar la probabilidad estad\u00edstica (valor p) con los intervalos de confianza. Aunque no podemos desarrollar el tema completamente aqu\u00ed, acepte que para datos distribuidos normalmente la media de los datos \u00b1 1,96 desviaciones est\u00e1ndar de la media (\u00b1 1,96 * DE) dividida por la ra\u00edz cuadrada del n\u00famero de observaciones de datos (\u00d6n) incluye 95 % de todos los valores plausibles del par\u00e1metro. Por lo tanto, si el valor del par\u00e1metro se encuentra dentro del intervalo \u00b1 (1,96 DE \/ \u00d6n), existe una probabilidad de \u00b3 95% de que el valor contradiga la hip\u00f3tesis. Para una prueba m\u00e1s estricta, podr\u00edamos requerir que la media del valor del par\u00e1metro se encuentre dentro de un intervalo de confianza del 99%, que es \u00b1 2.576 DE \/ \u00d6n de la media. En general, un intervalo de confianza estrecho indica informaci\u00f3n m\u00e1s precisa sobre el valor del par\u00e1metro, mientras que un intervalo amplio indica un mayor grado de incertidumbre.<\/p>\n<h3><strong>Comparaci\u00f3n de medias<\/strong><\/h3>\n<p>Para comparar las medias y comprobar si son diferentes, la estad\u00edstica proporciona una serie de pruebas. Por lo general, comenzamos por plantear una hip\u00f3tesis, por ejemplo, que los medios son en realidad los mismos; a esto lo llamamos la Hip\u00f3tesis nula. Luego, probamos la probabilidad de que las dos medias sean iguales y que la diferencia informada se deba simplemente al azar; expresamos esta probabilidad como una probabilidad que var\u00eda de 0 a 100% (0 a 1). Si la probabilidad de que las medias sean diferentes solo debido a una probabilidad aleatoria es muy peque\u00f1a (por ejemplo, menos del 5% (0,05)), entonces la probabilidad de que las medias (y las poblaciones de las que derivan) sean diferentes es mayor. En otras palabras, rechazar\u00edamos la Hip\u00f3tesis nula como falsa (o extremadamente improbable).<\/p>\n<p>Ejemplos de pruebas estad\u00edsticas para comparar medias incluyen la prueba <strong>t de Student<\/strong> y el <strong>an\u00e1lisis de varianza simple (ANOVA<\/strong>). Si realizamos una prueba t de Student en los conjuntos de datos y probamos la Hip\u00f3tesis nula (que las dos medias son iguales) al nivel de significancia del 5%, obtenemos un resultado de la prueba de la siguiente manera:<\/p>\n<p><a href=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5959\" src=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig1-300x213.png\" alt=\"\" width=\"550\" height=\"390\" srcset=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig1-300x213.png 300w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig1-1024x727.png 1024w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig1-768x545.png 768w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig1-600x426.png 600w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig1.png 1126w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a><\/p>\n<p>Tenemos la opci\u00f3n de elegir una prueba de <strong>una <\/strong>o<strong> dos colas<\/strong>: si no asumimos si la media del conjunto 2 es mayor o menor que la del conjunto 1, entonces deber\u00edamos elegir la prueba de 2 colas. Vemos que el valor de p es 0.166, que es mucho mayor que 0.05 (nivel de significancia del 5%). La prueba nos dice que hay evidencia inadecuada para rechazar la Hip\u00f3tesis Nula y que las medias no son significativamente diferentes. Tenga en cuenta que, si hubi\u00e9ramos probado que el conjunto medio 2 es mayor que el conjunto medio 1, entonces el valor p (de una cola) ser\u00eda 0.083, que est\u00e1 mucho m\u00e1s cerca de 0.05 pero a\u00fan no es significativo.<\/p>\n<p>Si agregamos otro conjunto, el Conjunto 3, que tiene un valor medio muy cercano al del Conjunto 2, pero arreglamos el conjunto para que tenga una varianza menor, podemos comparar los Conjuntos 1 y 3 usando la misma prueba. Los resultados se muestran a continuaci\u00f3n:<\/p>\n<p><a href=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig2.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5960\" src=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig2-300x220.png\" alt=\"\" width=\"500\" height=\"366\" srcset=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig2-300x220.png 300w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig2-768x563.png 768w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig2-600x440.png 600w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig2.png 1011w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>A simple vista, los medios se ven igualmente diferentes a los del ejemplo anterior. Sin embargo, tenga en cuenta que el conjunto de datos 3 tiene una varianza mucho menor que la que vimos para el conjunto 2. Ahora vemos que el valor p (de 2 colas) es 0,0014, que es mucho menor que 0,05. Esto nos dice que solo hay una probabilidad entre 1000 de que las medias sean diferentes por azar. Podemos rechazar la hip\u00f3tesis nula; los medios son significativamente diferentes.<\/p>\n<p>Si calculamos los intervalos de confianza (IC) del 95% para los conjuntos 1 y 2, encontramos para el conjunto 1 (4,36 a 6,8) y para el conjunto 2 (4,77 a 11,87). Obviamente, el IC del 95% para el conjunto 2 incluye la mayor\u00eda de los valores del IC para el conjunto 2, por lo que existe una probabilidad superior al 5% de que los conjuntos de datos provengan de la misma poblaci\u00f3n. Por el contrario, el IC del 95% para el conjunto 3 es (7,38 a 9,26) y no incluye los valores del IC del conjunto 1. Hay menos del 5% de probabilidad de que los datos del conjunto 1 provengan de la misma poblaci\u00f3n que los del conjunto 3.<sup>1<\/sup><\/p>\n<h3><strong>Comparar proporciones o distribuciones<\/strong><\/h3>\n<p>Un problema bastante com\u00fan en la pr\u00e1ctica cl\u00ednica es donde buscamos comparar dos poblaciones por las proporciones en cada una que indican una determinada caracter\u00edstica. Un ejemplo ser\u00edan 100 pacientes asignados al azar para recibir el tratamiento 1 o el tratamiento 2 (50 para cada grupo). El tratamiento se mide como \u00e9xito o fracaso. Si el Tratamiento-1 proporciona un 50% de \u00e9xito y el Tratamiento 2 un 65% de \u00e9xito, \u00bfson los dos tratamientos realmente diferentes o esta diferencia se debe \u00fanicamente al azar?<\/p>\n<p>Una vez m\u00e1s, las estad\u00edsticas proporcionan varios m\u00e9todos para comparar los dos tratamientos y proporcionar una medida de la verdadera diferencia. Declaramos la hip\u00f3tesis nula de que los dos tratamientos son igualmente efectivos y probamos la probabilidad de que esto sea cierto. La prueba de <strong>Chi-cuadrado <\/strong>(c2) es un ejemplo de una prueba que resolver\u00eda la pregunta planteada por el ejemplo anterior.<\/p>\n<p>Arriba se muestra una ilustraci\u00f3n simple de la prueba. Primero registramos los resultados de los tratamientos como se muestra en los <strong>datos observados<\/strong>. Para los tratamientos combinados, vemos que hubo un 58% de \u00e9xitos y un 42% de fracasos. Luego, configuramos una segunda tabla que atribuye a cada tratamiento estas tasas de \u00e9xito y fracaso con los n\u00fameros que hubi\u00e9ramos esperado si los resultados generales se aplicaran a ambos tratamientos; datos esperados. La prueba de Chi-cuadrado se usa luego para comparar los resultados observados y los <strong>resultados esperados<\/strong> y reporta un valor p. El valor p aqu\u00ed es 0,11, que es mayor que 0,05. La tasa de \u00e9xito aparentemente m\u00e1s alta para el Tratamiento 2 se producir\u00eda solo por casualidad en el 11% de los ensayos. Los resultados no indican que el Tratamiento 2 sea superior al Tratamiento 1.<\/p>\n<p>En el segundo ejemplo, el n\u00famero de sujetos en cada grupo aumenta, pero la diferencia en el \u00e9xito del tratamiento (aumento del 15%) para el tratamiento 2 en comparaci\u00f3n con el tratamiento 1 es proporcionalmente la misma. Ahora vemos que la diferencia es significativa con un valor de p 0.022, que es menor que 0.05. La raz\u00f3n por la que los dos ensayos producen resultados de significancia diferente es similar a la de cuando comparamos las medias anteriores; los n\u00fameros adicionales para este segundo ensayo tienen el efecto de reducir la varianza de los resultados y, por lo tanto, aumentan la importancia de la diferencia.<\/p>\n<p style=\"text-align: left;\" align=\"justify\"><a href=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig3.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5961\" src=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig3-233x300.png\" alt=\"\" width=\"324\" height=\"417\" srcset=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig3-233x300.png 233w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig3-600x773.png 600w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig3.png 604w\" sizes=\"auto, (max-width: 324px) 100vw, 324px\" \/><\/a><\/p>\n<p style=\"text-align: left;\" align=\"justify\">Los ejemplos aqu\u00ed de m\u00e9todos estad\u00edsticos para comparar datos y probar si la diferencia detectada se debe solo al azar o es significativa, solo brindan una visi\u00f3n m\u00ednima de los posibles m\u00e9todos disponibles, que son numerosos y pueden usarse para series de datos muy complicadas.<\/p>\n<p><em><sup> \u00a0\u00a0 1<\/sup> These confidence intervals are approximations which assume a completely normal distribution. More accurate CI can be calculated from the data.<\/em><\/p>\n<div class=\"vcex-spacing\" style=\"height:30px\"><\/div><div class=\"vcex-module vcex-divider vcex-divider-solid\" style=\"width:100%;margin-top:20px;margin-bottom:20px;border-top-width:1px;border-color:#dddddd;\"><\/div>\n<h4>Resources<\/h4>\n<p>Dawson B, Trapp RG. Chapter 8. Research Questions About Relationships among Variables. In: Dawson B, Trapp RG, eds. Basic &amp; Clinical Biostatistics. 4th ed. New York: McGraw-Hill; 2004.<\/p>\n<p>Walters RW, Kier KL. Chapter 8. The Application of Statistical Analysis in the Biomedical Sciences. In: Kier KL, Malone PM, Stanovich JE, eds. Drug Information: A Guide for Pharmacists. 4th ed. New York: McGraw-Hill; 2012.<\/p>\n<p>Godfrey K. Chapter 6. Testing for Relationships, Reporting Association and Correlation Analyses. In: Lang TA, Secic M, eds. How to Report Statistics in Medicine. 2nd ed. Philadelphia: American College of Physicians; 2006.<\/p>\n<p align=\"justify\">P\/N 101850-01S Rev B 02\/2023<\/p>\n<div class=\"vcex-spacing\" style=\"height:30px\"><\/div>\n","protected":false},"featured_media":0,"template":"","format":"standard","meta":{"_acf_changed":false},"categories":[274],"tags":[209],"language":[42],"articles":[231],"class_list":["post-5789","article","type-article","status-publish","format-standard","hentry","category-articulos","tag-basic-sp","language-spanish","articles-erc-ert","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comparaci\u00f3n, diferencia y significado - Advanced Renal Education Program<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comparaci\u00f3n, diferencia y significado - Advanced Renal Education Program\" \/>\n<meta property=\"og:description\" content=\"Si observamos las medias de los dos conjuntos de datos analizados en el art\u00edculo &#8220;Medidas de centralidad y dispersi\u00f3n&#8221;, podemos comparar la media del conjunto 1 (5,58) con la del conjunto 2 (8,32). Son evidentemente diferentes, pero \u00bfqu\u00e9 tan diferentes?&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"Advanced Renal Education Program\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-09T16:52:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1126\" \/>\n\t<meta property=\"og:image:height\" content=\"799\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/\",\"url\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/\",\"name\":\"Comparaci\u00f3n, diferencia y significado - Advanced Renal Education Program\",\"isPartOf\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig1-300x213.png\",\"datePublished\":\"2023-08-25T00:50:44+00:00\",\"dateModified\":\"2025-05-09T16:52:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/#primaryimage\",\"url\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig1.png\",\"contentUrl\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig1.png\",\"width\":1126,\"height\":799},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comparaci\u00f3n, diferencia y significado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#website\",\"url\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/\",\"name\":\"Advanced Renal Education Program\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#organization\",\"name\":\"Advanced Renal Education Program\",\"url\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/03\/1Asset-1.jpg\",\"contentUrl\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/03\/1Asset-1.jpg\",\"width\":1965,\"height\":381,\"caption\":\"Advanced Renal Education Program\"},\"image\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comparaci\u00f3n, diferencia y significado - Advanced Renal Education Program","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/","og_locale":"en_US","og_type":"article","og_title":"Comparaci\u00f3n, diferencia y significado - Advanced Renal Education Program","og_description":"Si observamos las medias de los dos conjuntos de datos analizados en el art\u00edculo &#8220;Medidas de centralidad y dispersi\u00f3n&#8221;, podemos comparar la media del conjunto 1 (5,58) con la del conjunto 2 (8,32). Son evidentemente diferentes, pero \u00bfqu\u00e9 tan diferentes?&hellip;","og_url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/","og_site_name":"Advanced Renal Education Program","article_modified_time":"2025-05-09T16:52:05+00:00","og_image":[{"width":1126,"height":799,"url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/","url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/","name":"Comparaci\u00f3n, diferencia y significado - Advanced Renal Education Program","isPartOf":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/#primaryimage"},"image":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/#primaryimage"},"thumbnailUrl":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig1-300x213.png","datePublished":"2023-08-25T00:50:44+00:00","dateModified":"2025-05-09T16:52:05+00:00","breadcrumb":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/#primaryimage","url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig1.png","contentUrl":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/101850_fig1.png","width":1126,"height":799},{"@type":"BreadcrumbList","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/comparacion-diferencia-y-significado-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ami.advancedrenaleducation.com\/wparep\/"},{"@type":"ListItem","position":2,"name":"Comparaci\u00f3n, diferencia y significado"}]},{"@type":"WebSite","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#website","url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/","name":"Advanced Renal Education Program","description":"","publisher":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ami.advancedrenaleducation.com\/wparep\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#organization","name":"Advanced Renal Education Program","url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#\/schema\/logo\/image\/","url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/03\/1Asset-1.jpg","contentUrl":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/03\/1Asset-1.jpg","width":1965,"height":381,"caption":"Advanced Renal Education Program"},"image":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#\/schema\/logo\/image\/"}}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Advanced Renal Education Program","distributor_original_site_url":"https:\/\/ami.advancedrenaleducation.com\/wparep","push-errors":false,"_links":{"self":[{"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/article\/5789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/media?parent=5789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/categories?post=5789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/tags?post=5789"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/language?post=5789"},{"taxonomy":"articles","embeddable":true,"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/articles?post=5789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}