

{"id":5808,"date":"2023-10-26T15:01:29","date_gmt":"2023-10-26T20:01:29","guid":{"rendered":"https:\/\/ami.advancedrenaleducation.com\/wparep\/?post_type=article&#038;p=5808"},"modified":"2025-05-09T10:54:15","modified_gmt":"2025-05-09T15:54:15","slug":"hemofiltracion-sp","status":"publish","type":"article","link":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/","title":{"rendered":"Hemofiltraci\u00f3n"},"content":{"rendered":"<h4>Hemofiltraci\u00f3n<\/h4>\n<p>Similar a la hemodi\u00e1lisis (HD), la hemofiltraci\u00f3n (HF) es una terapia dise\u00f1ada para mejorar el aclaramiento en pacientes que experimentan disfunci\u00f3n renal. La hemofiltraci\u00f3n se logra mediante un aclaramiento convectivo, en el que los solutos se transportan a trav\u00e9s de una membrana semipermeable, junto con el movimiento del solvente (ultrafiltraci\u00f3n) que ocurre en respuesta a un gradiente de presi\u00f3n transmembrana positivo (Figura 1). El aclaramiento depende de la velocidad de ultrafiltraci\u00f3n y las caracter\u00edsticas de tamizado de la membrana y el soluto y, en menor medida, del tama\u00f1o molecular del soluto. La hemofiltraci\u00f3n implica la eliminaci\u00f3n simult\u00e1nea de agua de plasma mediante ultrafiltraci\u00f3n y reemplazo con una soluci\u00f3n de electrolitos tamponada (l\u00edquido de reemplazo o reinfusi\u00f3n)<sup>1<\/sup>. Por lo general, el l\u00edquido de sustituci\u00f3n, una soluci\u00f3n esterilizada con electrolitos tamponada similar a la composici\u00f3n del agua de plasma, se administra antes o despu\u00e9s del filtro (es decir, modo de prediluci\u00f3n, modo de posdiluci\u00f3n) para tener en cuenta el agotamiento del plasma que se produce durante el procedimiento de di\u00e1lisis<sup>2<\/sup>. Esto contrasta con la HD, que se basa en un gradiente de concentraci\u00f3n (difusi\u00f3n) para la eliminaci\u00f3n de solutos<sup>3<\/sup>. Los estudios que comparan el aclaramiento convectivo y el aclaramiento difusivo han demostrado que las sustancias de peso molecular medio y las mol\u00e9culas grandes se eliminan mejor por convecci\u00f3n. A diferencia de la HD, la IC se utiliza con mayor frecuencia en casos de insuficiencia renal aguda, en un entorno de cuidados intensivos, y generalmente es un procedimiento prolongado y continuo, tambi\u00e9n conocido como terapia de reemplazo renal continuo, que a menudo dura 12 horas o m\u00e1s, con acceso generalmente logrado a trav\u00e9s de un cat\u00e9ter venoso central<sup>4<\/sup>.<\/p>\n<p><strong>Figura 1<sup>2<\/sup><\/strong><br \/>\n<a href=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/102547_fig1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-5978\" src=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/102547_fig1-236x300.png\" alt=\"\" width=\"191\" height=\"243\" srcset=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/102547_fig1-236x300.png 236w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/102547_fig1.png 377w\" sizes=\"auto, (max-width: 191px) 100vw, 191px\" \/><\/a><\/p>\n<h4>Principio:<\/h4>\n<p>Transferencia de solutos a trav\u00e9s de membranas semipermeables por flujo de agua inducido por presi\u00f3n<\/p>\n<ul>\n<li><em>fluido de sustituci\u00f3n<\/em> (prefiltro o postfiltro)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La cantidad de aclaramiento convectivo (K<sub>x<\/sub>) logrado durante HF se describe como el producto del coeficiente de tamizado respectivo (S<sub>x<\/sub>) y el flujo de ultrafiltraci\u00f3n a trav\u00e9s de la membrana (Q<sub>UF<\/sub>), o flujo total de agua, como se muestra en la figura 2. La tasa de soluto, por lo tanto, la eliminaci\u00f3n es proporcional a la presi\u00f3n aplicada, que puede ajustarse para satisfacer las necesidades de la situaci\u00f3n cl\u00ednica<sup>2<\/sup>.<\/p>\n<p><strong>Figura 2<\/strong><\/p>\n<p><a href=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig2.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5979\" src=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig2-300x134.png\" alt=\"\" width=\"438\" height=\"196\" srcset=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig2-300x134.png 300w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig2-600x268.png 600w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig2.png 681w\" sizes=\"auto, (max-width: 438px) 100vw, 438px\" \/><\/a><\/p>\n<p>La selectividad (permeabilidad) del proceso, o la capacidad de distinguir solutos de diferentes tama\u00f1os, est\u00e1 determinada exclusivamente por las propiedades de tamizado (filtrado) de la membrana. As\u00ed, el paso de un soluto por la membrana se describe mediante el coeficiente de tamizado (S), que es la relaci\u00f3n entre la concentraci\u00f3n de filtrado de soluto (C<sub>f<\/sub>) y la concentraci\u00f3n plasm\u00e1tica de soluto respectiva (C<sub>p<\/sub>), como se muestra en la figura 3. Un coeficiente de tamizado de uno indica transporte sin restricciones, mientras que una S de cero indica que el transporte est\u00e1 completamente restringido.<\/p>\n<p><strong>Figura 3<\/strong><br \/>\n<a href=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig3.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5980\" src=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig3-300x169.png\" alt=\"\" width=\"576\" height=\"324\" srcset=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig3-300x169.png 300w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig3-768x431.png 768w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig3-600x337.png 600w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig3.png 801w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/p>\n<p>Para una membrana dada, cada soluto tiene un coeficiente de tamizado espec\u00edfico, que depende de varios factores, incluido principalmente el tama\u00f1o del soluto en comparaci\u00f3n con el tama\u00f1o de los poros de la membrana, como se muestra en la figura 4<sup>5<\/sup>. Otros factores que determinan o influyen en el transporte o convecci\u00f3n de solutos incluyen forma y configuraci\u00f3n molecular, as\u00ed como posibles efectos de carga del soluto y la membrana. El transporte de solutos puede estar restringido o irrestricto, seg\u00fan estas propiedades de la membrana<sup>5<\/sup>.<\/p>\n<p><strong>Figure 4<\/strong><\/p>\n<p><a href=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig4.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5981\" src=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig4-171x300.png\" alt=\"\" width=\"161\" height=\"283\" srcset=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig4-171x300.png 171w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig4.png 313w\" sizes=\"auto, (max-width: 161px) 100vw, 161px\" \/><\/a><a href=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig4a.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5982\" src=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig4a-300x185.png\" alt=\"\" width=\"440\" height=\"272\" srcset=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig4a-300x185.png 300w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig4a-1024x632.png 1024w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig4a-768x474.png 768w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig4a-600x370.png 600w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig4a.png 1306w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/a><\/p>\n<p>Los coeficientes de tamizado se representan t\u00edpicamente frente al aumento de la masa molecular para ilustrar una curva de coeficiente de tamizado, como se muestra en la figura 5. El gr\u00e1fico que se muestra a continuaci\u00f3n representa las curvas de coeficiente de tamizado para diferentes tipos de membranas<sup>5<\/sup>.<\/p>\n<p><strong>Figura 5: Curva de coeficiente de tamizado y corte de MW (adaptado de Ronco, C. Y cols.6)<\/strong><\/p>\n<p><a href=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig5.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5983\" src=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig5-300x163.png\" alt=\"\" width=\"540\" height=\"293\" srcset=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig5-300x163.png 300w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig5-600x325.png 600w, https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/10\/102547_fig5.png 681w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a><\/p>\n<p>En resumen, la IC se basa en el transporte convectivo para eliminar solutos de la sangre de pacientes con insuficiencia renal. Este proceso requiere grandes cantidades de l\u00edquido de infusi\u00f3n est\u00e9ril para compensar la p\u00e9rdida de l\u00edquido del paciente. La HF se caracteriza por una mayor capacidad de eliminaci\u00f3n de solutos para solutos de MW m\u00e1s altos, pero es menos eficiente para solutos de MW peque\u00f1os en comparaci\u00f3n con HD. Esta diferencia se puede compensar aumentando los vol\u00famenes de intercambio. En la actualidad, la IC no se emplea ampliamente en el tratamiento de rutina de la enfermedad renal en etapa terminal y generalmente se usa en cuidados intensivos, en pacientes con insuficiencia renal aguda. Sin embargo, se est\u00e1 investigando la viabilidad de la IC diaria corta como alternativa a la HD intermitente<sup>7<\/sup> y podr\u00eda conducir a un mayor uso como terapia de reemplazo renal domiciliaria en el futuro.<\/p>\n<div class=\"vcex-spacing\" style=\"height:30px\"><\/div><div class=\"vcex-module vcex-divider vcex-divider-solid\" style=\"width:100%;margin-top:20px;margin-bottom:20px;border-top-width:1px;border-color:#dddddd;\"><\/div>\n<h4><strong>Referencias<\/strong><\/h4>\n<ol>\n<li>Huang Z, Letteri JJ, Ronco C, Gao D, Clark WR. CHAPTER 249 &#8211; Predilution and Postdilution Reinfusion Techniques. In: Ronco C, Bellomo R, Kellum JABT-CCN (Second E, eds. Philadelphia: W.B. Saunders; 2009:1370-1374.<\/li>\n<li>Ledebo I. Principles and practice of hemofiltration and hemodiafiltration. <em>Artif Organs<\/em>. 1998;22(1):20-25. www.ncbi.nlm.nih.gov\/pubmed\/9456222<\/li>\n<li>Golper TA, Fissell R, Fissell WH, Hartle PM, Sanders ML, Schulman G. Hemodialysis: core curriculum 2014. <em>Am J kidney Dis Off J Natl Kidney\u00a0 Found<\/em>. 2014;63(1):153-163. www.ncbi.nlm.nih.gov\/pubmed\/24268927<\/li>\n<li>Saunders H SD. Continuous Renal Replacement Therapy. <em>StatPearls [Internet]<\/em>.<\/li>\n<li>Neri M, Villa G, Garzotto F, Bagshaw S, Bellomo R, Cerda J, Ferrari F, Guggia S, Joannidis M, Kellum J, Kim JC, Mehta RL, Ricci Z, Trevisani A, Marafon S, Clark WR, Vincent J-L, Ronco C, alliance NSI (NSI). Nomenclature for renal replacement therapy in acute kidney injury: basic principles. <em>Crit Care<\/em>. 2016;20(1):318.<\/li>\n<li>Ronco C, La Manna G. Expanded Hemodialysis: A New Therapy for a New Class of Membranes. <em>Contrib Nephrol<\/em>. 2017;190:124-133. www.ncbi.nlm.nih.gov\/pubmed\/28535525<\/li>\n<li>Jaber BL, Zimmerman DL. DAILY HEMODIALYSIS\u2014SELECTED TOPICS: Rationale and Experience with Short Daily Hemofiltration. <em>Semin Dial<\/em>. 2004;17(2):146-150.<\/li>\n<\/ol>\n<p>P\/N 102547-01S Rev B 02\/2023<\/p>\n<div class=\"vcex-spacing\" style=\"height:30px\"><\/div>\n","protected":false},"featured_media":0,"template":"","format":"standard","meta":{"_acf_changed":false},"categories":[274],"tags":[220],"language":[42],"articles":[272],"class_list":["post-5808","article","type-article","status-publish","format-standard","hentry","category-articulos","tag-modalities-sp","language-spanish","articles-hemodialisis","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hemofiltraci\u00f3n - Advanced Renal Education Program<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hemofiltraci\u00f3n - Advanced Renal Education Program\" \/>\n<meta property=\"og:description\" content=\"Hemofiltraci\u00f3n Similar a la hemodi\u00e1lisis (HD), la hemofiltraci\u00f3n (HF) es una terapia dise\u00f1ada para mejorar el aclaramiento en pacientes que experimentan disfunci\u00f3n renal. La hemofiltraci\u00f3n se logra mediante un aclaramiento convectivo, en el que los solutos se transportan a trav\u00e9s&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"Advanced Renal Education Program\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-09T15:54:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/102547_fig1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"377\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/\",\"url\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/\",\"name\":\"Hemofiltraci\u00f3n - Advanced Renal Education Program\",\"isPartOf\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/102547_fig1-236x300.png\",\"datePublished\":\"2023-10-26T20:01:29+00:00\",\"dateModified\":\"2025-05-09T15:54:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/#primaryimage\",\"url\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/102547_fig1.png\",\"contentUrl\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/102547_fig1.png\",\"width\":377,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hemofiltraci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#website\",\"url\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/\",\"name\":\"Advanced Renal Education Program\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#organization\",\"name\":\"Advanced Renal Education Program\",\"url\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/03\/1Asset-1.jpg\",\"contentUrl\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/03\/1Asset-1.jpg\",\"width\":1965,\"height\":381,\"caption\":\"Advanced Renal Education Program\"},\"image\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hemofiltraci\u00f3n - Advanced Renal Education Program","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/","og_locale":"en_US","og_type":"article","og_title":"Hemofiltraci\u00f3n - Advanced Renal Education Program","og_description":"Hemofiltraci\u00f3n Similar a la hemodi\u00e1lisis (HD), la hemofiltraci\u00f3n (HF) es una terapia dise\u00f1ada para mejorar el aclaramiento en pacientes que experimentan disfunci\u00f3n renal. La hemofiltraci\u00f3n se logra mediante un aclaramiento convectivo, en el que los solutos se transportan a trav\u00e9s&hellip;","og_url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/","og_site_name":"Advanced Renal Education Program","article_modified_time":"2025-05-09T15:54:15+00:00","og_image":[{"width":377,"height":480,"url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/102547_fig1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/","url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/","name":"Hemofiltraci\u00f3n - Advanced Renal Education Program","isPartOf":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/#primaryimage"},"image":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/#primaryimage"},"thumbnailUrl":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/102547_fig1-236x300.png","datePublished":"2023-10-26T20:01:29+00:00","dateModified":"2025-05-09T15:54:15+00:00","breadcrumb":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/#primaryimage","url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/102547_fig1.png","contentUrl":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/08\/102547_fig1.png","width":377,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/hemofiltracion-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ami.advancedrenaleducation.com\/wparep\/"},{"@type":"ListItem","position":2,"name":"Hemofiltraci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#website","url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/","name":"Advanced Renal Education Program","description":"","publisher":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ami.advancedrenaleducation.com\/wparep\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#organization","name":"Advanced Renal Education Program","url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#\/schema\/logo\/image\/","url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/03\/1Asset-1.jpg","contentUrl":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/03\/1Asset-1.jpg","width":1965,"height":381,"caption":"Advanced Renal Education Program"},"image":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#\/schema\/logo\/image\/"}}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Advanced Renal Education Program","distributor_original_site_url":"https:\/\/ami.advancedrenaleducation.com\/wparep","push-errors":false,"_links":{"self":[{"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/article\/5808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/media?parent=5808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/categories?post=5808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/tags?post=5808"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/language?post=5808"},{"taxonomy":"articles","embeddable":true,"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/articles?post=5808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}