

{"id":5842,"date":"2023-08-28T13:13:42","date_gmt":"2023-08-28T18:13:42","guid":{"rendered":"https:\/\/ami.advancedrenaleducation.com\/wparep\/?post_type=article&#038;p=5842"},"modified":"2025-05-09T11:00:12","modified_gmt":"2025-05-09T16:00:12","slug":"fistula-arteriovenosa-fav-sp","status":"publish","type":"article","link":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/fistula-arteriovenosa-fav-sp\/","title":{"rendered":"F\u00edstula arteriovenosa (FAV)"},"content":{"rendered":"<h4><strong>F\u00edstula arteriovenosa (FAV)<\/strong><\/h4>\n<p>Una FAV es el resultado de una anastomosis quir\u00fargica directa entre una arteria y una vena. Esta comunicaci\u00f3n directa permite que la vena aumente de tama\u00f1o y se &#8220;arterialice&#8221; debido al aumento de la presi\u00f3n transmitida desde la arteria<sup>1<\/sup>. Algunos autores se refieren a la arterializaci\u00f3n como remodelaci\u00f3n venosa porque todo el lecho vascular debe sufrir una remodelaci\u00f3n dram\u00e1tica para adaptarse a las tasas de flujo sangu\u00edneo que se han incrementado en un factor de 10 a 50 veces sobre los valores basales<sup>2<\/sup>.<\/p>\n<p>Aunque son posibles varias formas de FAV, la construcci\u00f3n cl\u00e1sica de FAV involucra la arteria radial y la vena cef\u00e1lica en la mu\u00f1eca (f\u00edstula radiocef\u00e1lica, mu\u00f1eca o Cimino), la arteria braquial y la vena cef\u00e1lica en la fosa anticubital (f\u00edstula braquiocef\u00e1lica o de la parte superior del brazo) o arteria braquial y vena bas\u00edlica (f\u00edstula braquiobas\u00edlica transpuesta) en la parte superior del brazo. Tanto las gu\u00edas estadounidenses como las canadienses recomiendan comenzar con la f\u00edstula del vaso nativo m\u00e1s distal posible (preferiblemente la radiocef\u00e1lica) <sup>3,4<\/sup>. Las f\u00edstulas braquiocef\u00e1lica y braquiobas\u00edlica son la segunda y tercera opci\u00f3n, respectivamente<sup>4<\/sup>. Este orden de colocaci\u00f3n de la FAV permite la creaci\u00f3n posterior de una FAV m\u00e1s proximal si la FAV distal se vuelve inutilizable. Es preferible la selecci\u00f3n del brazo no dominante para facilitar las actividades de la vida diaria<sup>4<\/sup>.<\/p>\n<p>Cuando no es posible la construcci\u00f3n cl\u00e1sica de una FAV, se pueden crear f\u00edstulas alternativas en la extremidad superior mediante la conexi\u00f3n de la arteria cubital y la vena bas\u00edlica<sup>4<\/sup>. Las f\u00edstulas en la extremidad inferior, como la femoral com\u00fan femoral superficial con transposiciones del muslo, son raras debido a su inconveniente ubicaci\u00f3n y preocupaciones sobre el posible desarrollo de isquemia distal. Sin embargo, se han informado resultados adecuados (en particular, disminuci\u00f3n de la isquemia posoperatoria) con la selecci\u00f3n adecuada de pacientes y la reducci\u00f3n selectiva de la vena femoral intraoperatoria<sup>5<\/sup>.<\/p>\n<p>Las decisiones de acceso tienen un impacto significativo en el resultado del paciente<sup>6<\/sup>. Los datos del Sistema de Datos Renales de los Estados Unidos (USRDS) confirman que las FAV tienen las tasas de complicaciones m\u00e1s bajas de todos los accesos vasculares disponibles (0,64 procedimientos por paciente y a\u00f1o frente a 1,61 para los injertos arteriovenosos (IAV) <sup>6,7<\/sup>. Tanto los pacientes diab\u00e9ticos como los no diab\u00e9ticos con FAV tienen un riesgo relativo de muerte significativamente menor que aquellos con IAV y cat\u00e9ter<sup>8,9<\/sup>. Por estas razones, las Directrices de pr\u00e1ctica cl\u00ednica para el acceso vascular de la National Kidney Foundation-Dialysis Outcomes Quality Initiative (KDOQI) recomiendan la colocaci\u00f3n de un acceso de FAV en lugar de IAV o di\u00e1lisis Se recomienda la colocaci\u00f3n de la FAV al menos 6 meses antes del inicio de la HD cr\u00f3nica para dejar tiempo suficiente para la maduraci\u00f3n de la FAV y para una posible revisi\u00f3n<sup>4<\/sup>.<\/p>\n<p>Una FAV funcional puede ser dif\u00edcil de lograr en algunas poblaciones de pacientes. La elecci\u00f3n de una arteria y una vena &#8220;sanas&#8221; adecuadas, junto con una t\u00e9cnica quir\u00fargica experta, es fundamental para una maduraci\u00f3n adecuada y el \u00e9xito de la FAV a largo plazo<sup>2<\/sup>.<\/p>\n<p>La derivaci\u00f3n oportuna a un nefr\u00f3logo y las im\u00e1genes preoperatorias para evaluar la presencia de una arteria de entrada y una vena de salida adecuadas es un requisito previo para la colocaci\u00f3n adecuada de la FAV<sup>6<\/sup>. Los resultados de la di\u00e1lisis y los patrones de pr\u00e1ctica (DOPPS) III informan que los pacientes ten\u00edan menos probabilidades de utilizar una FAV si eran mujeres, ten\u00edan un mayor \u00edndice de masa corporal o ten\u00edan diabetes, enfermedad vascular perif\u00e9rica o celulitis \/ gangrena recurrente<sup>10<\/sup>. Estas caracter\u00edsticas de los pacientes est\u00e1n asociadas a una alta tasa de fracaso primario de la FAV (aproximadamente el 40% )<sup>11<\/sup>.<\/p>\n<div class=\"vcex-spacing\" style=\"height:30px\"><\/div><div class=\"vcex-module vcex-divider vcex-divider-solid\" style=\"width:100%;margin-top:20px;margin-bottom:20px;border-top-width:1px;border-color:#dddddd;\"><\/div>\n<h4><strong>Referencias<\/strong>:<\/h4>\n<ol>\n<li>Sands JJ. Vascular access 2007. <em>Minerva Urol Nefrol<\/em>. 2007;59(3):237-249. Available from: http:\/\/www.ncbi.nlm.nih.gov\/pubmed\/17912221.<\/li>\n<li>Konner K. The anastomosis of the arteriovenous fistula\u2014common errors and their avoidance. <em>Nephrol Dial Transpl<\/em>. 2002;17:376-379. Available from: https:\/\/pubmed.ncbi.nlm.nih.gov\/11865080\/.<\/li>\n<li>Culleton BF, Chan CT, Deziel C, et al. Hemodialysis clinical practice guidelines for the Canadian Society of Nephrology. <em>J Am Soc Nephrol<\/em>. 2006;17(3 Suppl 1):S1-27. Available from: http:\/\/www.ncbi.nlm.nih.gov\/pubmed\/16497879.<\/li>\n<li>Lok CE, Huber TS, Lee T, et al. KDOQI Clinical Practice Guideline for Vascular Access: 2019 Update. <em>Am J Kidney Dis<\/em>. 2020;75(4):S1-S164. Available from: https:\/\/pubmed.ncbi.nlm.nih.gov\/32778223\/.<\/li>\n<li>Gradman WS, Laub J, Cohen W. Femoral vein transposition for arteriovenous hemodialysis access: Improved patient selection and intraoperative measures reduce postoperative ischemia. <em>J Vasc Surg<\/em>. 2005;41(2):279-284. Available from: http:\/\/www.ncbi.nlm.nih.gov\/pubmed\/15768010.<\/li>\n<li>Sands JJ. Vascular access: the past, present and future. <em>Blood Purif<\/em>. 2009;27(1):22-27. Available from: http:\/\/www.ncbi.nlm.nih.gov\/pubmed\/19169013.<\/li>\n<li>United States Renal Data System. 2019 USRDS Annual Data Report: Epidemiology of kidney disease in the United States. National Institutes of Health, National Institute of Diabetes and Digestive and Kidney Diseases, Bethesda, MD, 2019. Available from: https:\/\/www.usrds.org\/annual-data-report\/.<\/li>\n<li>Dhingra RK, Young EW, Hulbert-Shearon TE, Leavey SF, Port FK. Type of vascular access and mortality in U.S. hemodialysis patients. <em>Kidney Int<\/em>. 2001;60(4):1443-1451. Available from: http:\/\/www.ncbi.nlm.nih.gov\/pubmed\/11576358.<\/li>\n<li>Pastan S, Soucie JM, McClellan WM. Vascular access and increased risk of death among hemodialysis patients. <em>Kidney Int<\/em>. 2002;62(2):620-626. Available from: http:\/\/www.ncbi.nlm.nih.gov\/pubmed\/12110026.<\/li>\n<li>Ethier J, Mendelssohn DC, Elder SJ, et al. Vascular access use and outcomes: an international perspective from the Dialysis Outcomes and Practice Patterns Study. <em>Nephrol Dial Transplant<\/em>. 2008;23(10):3219-3226. Available from: https:\/\/pubmed.ncbi.nlm.nih.gov\/18511606\/.<\/li>\n<li>Maya ID, Allon M. Vascular Access: Core Curriculum 2008. <em>Am J Kidney Dis<\/em>. 2008;51(4):702-708. Available from: http:\/\/www.ncbi.nlm.nih.gov\/pubmed\/18371547.<\/li>\n<\/ol>\n<p>P\/N 101032-01S Rev A 02\/2023<\/p>\n<div class=\"vcex-spacing\" style=\"height:30px\"><\/div>\n","protected":false},"featured_media":0,"template":"","format":"standard","meta":{"_acf_changed":false},"categories":[274],"tags":[208],"language":[42],"articles":[272],"class_list":["post-5842","article","type-article","status-publish","format-standard","hentry","category-articulos","tag-access-sp","language-spanish","articles-hemodialisis","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>F\u00edstula arteriovenosa (FAV) - Advanced Renal Education Program<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/fistula-arteriovenosa-fav-sp\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00edstula arteriovenosa (FAV) - Advanced Renal Education Program\" \/>\n<meta property=\"og:description\" content=\"F\u00edstula arteriovenosa (FAV) Una FAV es el resultado de una anastomosis quir\u00fargica directa entre una arteria y una vena. Esta comunicaci\u00f3n directa permite que la vena aumente de tama\u00f1o y se &#8220;arterialice&#8221; debido al aumento de la presi\u00f3n transmitida desde&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/fistula-arteriovenosa-fav-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"Advanced Renal Education Program\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-09T16:00:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/fistula-arteriovenosa-fav-sp\/\",\"url\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/fistula-arteriovenosa-fav-sp\/\",\"name\":\"F\u00edstula arteriovenosa (FAV) - Advanced Renal Education Program\",\"isPartOf\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#website\"},\"datePublished\":\"2023-08-28T18:13:42+00:00\",\"dateModified\":\"2025-05-09T16:00:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/fistula-arteriovenosa-fav-sp\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/fistula-arteriovenosa-fav-sp\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/fistula-arteriovenosa-fav-sp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00edstula arteriovenosa (FAV)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#website\",\"url\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/\",\"name\":\"Advanced Renal Education Program\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#organization\",\"name\":\"Advanced Renal Education Program\",\"url\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/03\/1Asset-1.jpg\",\"contentUrl\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/03\/1Asset-1.jpg\",\"width\":1965,\"height\":381,\"caption\":\"Advanced Renal Education Program\"},\"image\":{\"@id\":\"https:\/\/ami.advancedrenaleducation.com\/wparep\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00edstula arteriovenosa (FAV) - Advanced Renal Education Program","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/fistula-arteriovenosa-fav-sp\/","og_locale":"en_US","og_type":"article","og_title":"F\u00edstula arteriovenosa (FAV) - Advanced Renal Education Program","og_description":"F\u00edstula arteriovenosa (FAV) Una FAV es el resultado de una anastomosis quir\u00fargica directa entre una arteria y una vena. Esta comunicaci\u00f3n directa permite que la vena aumente de tama\u00f1o y se &#8220;arterialice&#8221; debido al aumento de la presi\u00f3n transmitida desde&hellip;","og_url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/fistula-arteriovenosa-fav-sp\/","og_site_name":"Advanced Renal Education Program","article_modified_time":"2025-05-09T16:00:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/fistula-arteriovenosa-fav-sp\/","url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/fistula-arteriovenosa-fav-sp\/","name":"F\u00edstula arteriovenosa (FAV) - Advanced Renal Education Program","isPartOf":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#website"},"datePublished":"2023-08-28T18:13:42+00:00","dateModified":"2025-05-09T16:00:12+00:00","breadcrumb":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/fistula-arteriovenosa-fav-sp\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/fistula-arteriovenosa-fav-sp\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/article\/fistula-arteriovenosa-fav-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ami.advancedrenaleducation.com\/wparep\/"},{"@type":"ListItem","position":2,"name":"F\u00edstula arteriovenosa (FAV)"}]},{"@type":"WebSite","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#website","url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/","name":"Advanced Renal Education Program","description":"","publisher":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ami.advancedrenaleducation.com\/wparep\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#organization","name":"Advanced Renal Education Program","url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#\/schema\/logo\/image\/","url":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/03\/1Asset-1.jpg","contentUrl":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-content\/uploads\/2023\/03\/1Asset-1.jpg","width":1965,"height":381,"caption":"Advanced Renal Education Program"},"image":{"@id":"https:\/\/ami.advancedrenaleducation.com\/wparep\/#\/schema\/logo\/image\/"}}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Advanced Renal Education Program","distributor_original_site_url":"https:\/\/ami.advancedrenaleducation.com\/wparep","push-errors":false,"_links":{"self":[{"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/article\/5842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/media?parent=5842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/categories?post=5842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/tags?post=5842"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/language?post=5842"},{"taxonomy":"articles","embeddable":true,"href":"https:\/\/ami.advancedrenaleducation.com\/wparep\/wp-json\/wp\/v2\/articles?post=5842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}